{"id":630,"count":1,"description":"","link":"https:\/\/www.neoprexmaurer.com.br\/blog\/tag\/juntas-de-dilatacao-em-estruturas-de-concreto\/","name":"juntas de dilata\u00e7\u00e3o em estruturas de concreto","slug":"juntas-de-dilatacao-em-estruturas-de-concreto","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Arquivo de juntas de dilata\u00e7\u00e3o em estruturas de concreto - Blog Maurer do Brasil<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.neoprexmaurer.com.br\/blog\/tag\/juntas-de-dilatacao-em-estruturas-de-concreto\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arquivo de juntas de dilata\u00e7\u00e3o em estruturas de concreto - Blog Maurer do Brasil\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.neoprexmaurer.com.br\/blog\/tag\/juntas-de-dilatacao-em-estruturas-de-concreto\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Maurer do Brasil\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.neoprexmaurer.com.br\/blog\/tag\/juntas-de-dilatacao-em-estruturas-de-concreto\/\",\"url\":\"https:\/\/www.neoprexmaurer.com.br\/blog\/tag\/juntas-de-dilatacao-em-estruturas-de-concreto\/\",\"name\":\"Arquivo de juntas de dilata\u00e7\u00e3o em estruturas de concreto - Blog Maurer do Brasil\",\"isPartOf\":{\"@id\":\"https:\/\/www.neoprexmaurer.com.br\/blog\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.neoprexmaurer.com.br\/blog\/tag\/juntas-de-dilatacao-em-estruturas-de-concreto\/#breadcrumb\"},\"inLanguage\":\"pt-BR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.neoprexmaurer.com.br\/blog\/tag\/juntas-de-dilatacao-em-estruturas-de-concreto\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.neoprexmaurer.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"juntas de dilata\u00e7\u00e3o em estruturas de concreto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.neoprexmaurer.com.br\/blog\/#website\",\"url\":\"https:\/\/www.neoprexmaurer.com.br\/blog\/\",\"name\":\"Blog Maurer do Brasil\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.neoprexmaurer.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.neoprexmaurer.com.br\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.neoprexmaurer.com.br\/blog\/#organization\",\"name\":\"Blog Maurer do Brasil\",\"url\":\"https:\/\/www.neoprexmaurer.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.neoprexmaurer.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.neoprexmaurer.com.br\/blog\/wp-content\/uploads\/2024\/07\/cropped-logo-7-1.png\",\"contentUrl\":\"https:\/\/www.neoprexmaurer.com.br\/blog\/wp-content\/uploads\/2024\/07\/cropped-logo-7-1.png\",\"width\":310,\"height\":88,\"caption\":\"Blog Maurer do Brasil\"},\"image\":{\"@id\":\"https:\/\/www.neoprexmaurer.com.br\/blog\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arquivo de juntas de dilata\u00e7\u00e3o em estruturas de concreto - Blog Maurer do Brasil","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.neoprexmaurer.com.br\/blog\/tag\/juntas-de-dilatacao-em-estruturas-de-concreto\/","og_locale":"pt_BR","og_type":"article","og_title":"Arquivo de juntas de dilata\u00e7\u00e3o em estruturas de concreto - Blog Maurer do Brasil","og_url":"https:\/\/www.neoprexmaurer.com.br\/blog\/tag\/juntas-de-dilatacao-em-estruturas-de-concreto\/","og_site_name":"Blog Maurer do Brasil","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.neoprexmaurer.com.br\/blog\/tag\/juntas-de-dilatacao-em-estruturas-de-concreto\/","url":"https:\/\/www.neoprexmaurer.com.br\/blog\/tag\/juntas-de-dilatacao-em-estruturas-de-concreto\/","name":"Arquivo de juntas de dilata\u00e7\u00e3o em estruturas de concreto - Blog Maurer do Brasil","isPartOf":{"@id":"https:\/\/www.neoprexmaurer.com.br\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.neoprexmaurer.com.br\/blog\/tag\/juntas-de-dilatacao-em-estruturas-de-concreto\/#breadcrumb"},"inLanguage":"pt-BR"},{"@type":"BreadcrumbList","@id":"https:\/\/www.neoprexmaurer.com.br\/blog\/tag\/juntas-de-dilatacao-em-estruturas-de-concreto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.neoprexmaurer.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"juntas de dilata\u00e7\u00e3o em estruturas de concreto"}]},{"@type":"WebSite","@id":"https:\/\/www.neoprexmaurer.com.br\/blog\/#website","url":"https:\/\/www.neoprexmaurer.com.br\/blog\/","name":"Blog Maurer do Brasil","description":"","publisher":{"@id":"https:\/\/www.neoprexmaurer.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.neoprexmaurer.com.br\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.neoprexmaurer.com.br\/blog\/#organization","name":"Blog Maurer do Brasil","url":"https:\/\/www.neoprexmaurer.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.neoprexmaurer.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.neoprexmaurer.com.br\/blog\/wp-content\/uploads\/2024\/07\/cropped-logo-7-1.png","contentUrl":"https:\/\/www.neoprexmaurer.com.br\/blog\/wp-content\/uploads\/2024\/07\/cropped-logo-7-1.png","width":310,"height":88,"caption":"Blog Maurer do Brasil"},"image":{"@id":"https:\/\/www.neoprexmaurer.com.br\/blog\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.neoprexmaurer.com.br\/blog\/wp-json\/wp\/v2\/tags\/630","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.neoprexmaurer.com.br\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.neoprexmaurer.com.br\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.neoprexmaurer.com.br\/blog\/wp-json\/wp\/v2\/posts?tags=630"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}